{"id":2,"date":"2024-02-29T17:52:33","date_gmt":"2024-02-29T20:52:33","guid":{"rendered":"http:\/\/juntamaldonado.com\/?page_id=2"},"modified":"2024-02-29T17:52:33","modified_gmt":"2024-02-29T20:52:33","slug":"pagina-ejemplo","status":"publish","type":"page","link":"https:\/\/juntamaldonado.com\/index.php\/pagina-ejemplo\/","title":{"rendered":"P\u00e1gina de ejemplo"},"content":{"rendered":"\n<p>Esta es una p\u00e1gina de ejemplo. Es diferente a una entrada del blog porque permanecer\u00e1 en un solo lugar y aparecer\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de las personas comienzan con una p\u00e1gina &#8220;Acerca de&#8221; que los presenta a los visitantes potenciales del sitio. Podr\u00edas decir algo as\u00ed:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>\u00a1Hola! Soy mensajero en bicicleta de d\u00eda, actor aspirante de noche, y esta es mi p\u00e1gina web. Vivo en Los \u00c1ngeles, tengo un gran perro llamado Jack, y me gustan las pi\u00f1as coladas. (Y ser atrapado por la lluvia.)<\/p><\/blockquote>\n\n\n\n<p>&#8230;o algo como esto:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>La compa\u00f1ia XYZ Trasto fue fundada en 1971, y provee trastos de calidad para el p\u00fablico desde entonces. Ubicado en Ciudad G\u00f3tica, XYZ le da empleo a m\u00e1s de 2000 personas y hace todo tipo de cosas asombrosas para la comunidad de G\u00f3tica.<\/p><\/blockquote>\n\n\n\n<p>Como nuevo usuario de WordPress, deber\u00edas dirigirte a <a href=\"http:\/\/juntamaldonado.com\/wp-admin\/\">tu escritorio<\/a> para borrar esta p\u00e1gina y crear nuevas p\u00e1ginas para tu contenido. \u00a1Divertite!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta es una p\u00e1gina de ejemplo. Es diferente a una entrada del blog porque permanecer\u00e1 en un solo lugar y aparecer\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de las personas comienzan con una p\u00e1gina &#8220;Acerca de&#8221; que los presenta a los visitantes potenciales del sitio. Podr\u00edas decir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/pages\/2"}],"collection":[{"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/juntamaldonado.com\/index.php\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}